{"id":10181,"date":"2022-06-05T15:08:09","date_gmt":"2022-06-05T12:08:09","guid":{"rendered":"https:\/\/www.saypro.com.tr\/?page_id=10181"},"modified":"2025-05-26T10:40:28","modified_gmt":"2025-05-26T07:40:28","slug":"hnc-electric","status":"publish","type":"page","link":"https:\/\/www.saypro.com.tr\/en\/hnc-electric\/","title":{"rendered":"HNC Electric"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10181\" class=\"elementor elementor-10181 elementor-9406\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f02d87f ot-traditional elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f02d87f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f08d09 ot-flex-column-vertical\" data-id=\"5f08d09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5cd681 elementor-widget elementor-widget-spacer\" data-id=\"a5cd681\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31b5102 ot-traditional elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31b5102\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-85a510f ot-flex-column-vertical\" data-id=\"85a510f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cae7446 elementor-widget elementor-widget-image\" data-id=\"cae7446\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/urun-kategorileri\/ac-surucu-urunleri\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/hv10.jpg\" class=\"attachment-large size-large wp-image-9316\" alt=\"\" srcset=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/hv10.jpg 500w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/hv10-300x300.jpg 300w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/hv10-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e88a14b ot-flex-column-vertical\" data-id=\"e88a14b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d676e8 elementor-widget elementor-widget-image\" data-id=\"2d676e8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/urun-kategorileri\/plc-kontrolor\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HCG-serisi-kart-1.jpg\" class=\"attachment-large size-large wp-image-9283\" alt=\"\" srcset=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HCG-serisi-kart-1.jpg 500w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HCG-serisi-kart-1-300x300.jpg 300w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HCG-serisi-kart-1-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e6886b1 ot-flex-column-vertical\" data-id=\"e6886b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10ba8be elementor-widget elementor-widget-image\" data-id=\"10ba8be\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/urun-kategorileri\/servo-motor-ve-kontrol\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HSD7-E-serisi-1.jpg\" class=\"attachment-large size-large wp-image-9293\" alt=\"\" srcset=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HSD7-E-serisi-1.jpg 500w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HSD7-E-serisi-1-300x300.jpg 300w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/HSD7-E-serisi-1-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04db1c0 ot-traditional elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04db1c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a2b785b ot-flex-column-vertical\" data-id=\"a2b785b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c03246 elementor-align-center elementor-widget elementor-widget-ibutton\" data-id=\"5c03246\" data-element_type=\"widget\" data-widget_type=\"ibutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-button\">\r\n\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/en\/product-categories\/ac-drive-products\/\" class=\"octf-btn octf-btn-primary\">AC Drive Products<\/a>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-109d356 ot-flex-column-vertical\" data-id=\"109d356\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ba6454 elementor-align-center elementor-widget elementor-widget-ibutton\" data-id=\"3ba6454\" data-element_type=\"widget\" data-widget_type=\"ibutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-button\">\r\n\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/en\/product-categories\/plc-kontrolor-hnc-electric\/\" class=\"octf-btn octf-btn-primary\">PLC Controller<\/a>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ad61f9 ot-flex-column-vertical\" data-id=\"7ad61f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87614c8 elementor-align-center elementor-widget elementor-widget-ibutton\" data-id=\"87614c8\" data-element_type=\"widget\" data-widget_type=\"ibutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-button\">\r\n\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/en\/product-categories\/servo-motor-and-control\/\" class=\"octf-btn octf-btn-primary\">Servo Motor and Control<\/a>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f47d5fb ot-traditional elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f47d5fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d844455 ot-flex-column-vertical\" data-id=\"d844455\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaba110 elementor-widget elementor-widget-image\" data-id=\"aaba110\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/urun-kategorileri\/hmi-panel\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/ht26-1.jpeg\" class=\"attachment-large size-large wp-image-9312\" alt=\"\" srcset=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/ht26-1.jpeg 500w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/ht26-1-300x300.jpeg 300w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/ht26-1-150x150.jpeg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2cf87eb ot-flex-column-vertical\" data-id=\"2cf87eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fa04bf elementor-widget elementor-widget-image\" data-id=\"7fa04bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/urun-kategorileri\/cnc-kontrolor\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/808xpT3.jpeg\" class=\"attachment-large size-large wp-image-9334\" alt=\"\" srcset=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/808xpT3.jpeg 600w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/808xpT3-300x300.jpeg 300w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/808xpT3-150x150.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7b53de5 ot-flex-column-vertical\" data-id=\"7b53de5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7870f8f elementor-widget elementor-widget-image\" data-id=\"7870f8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/urun-kategorileri\/endustriyel-robot\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/JR612.jpeg\" class=\"attachment-large size-large wp-image-9337\" alt=\"\" srcset=\"https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/JR612.jpeg 600w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/JR612-300x300.jpeg 300w, https:\/\/www.saypro.com.tr\/wp-content\/uploads\/2021\/12\/JR612-150x150.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3825bb3 ot-traditional elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3825bb3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6460a5d ot-flex-column-vertical\" data-id=\"6460a5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8095a2c elementor-align-center elementor-widget elementor-widget-ibutton\" data-id=\"8095a2c\" data-element_type=\"widget\" data-widget_type=\"ibutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-button\">\r\n\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/en\/product-categories\/hmi-panel-hnc-electric\/\" class=\"octf-btn octf-btn-primary\">HMI Panel<\/a>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-32d4b2d ot-flex-column-vertical\" data-id=\"32d4b2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bb4d21 elementor-align-center elementor-widget elementor-widget-ibutton\" data-id=\"5bb4d21\" data-element_type=\"widget\" data-widget_type=\"ibutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-button\">\r\n\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/en\/product-categories\/cnc-controller\/\" class=\"octf-btn octf-btn-primary\">CNC Controller<\/a>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d471970 ot-flex-column-vertical\" data-id=\"d471970\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fe8ebc elementor-align-center elementor-widget elementor-widget-ibutton\" data-id=\"3fe8ebc\" data-element_type=\"widget\" data-widget_type=\"ibutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-button\">\r\n\t\t\t<a href=\"https:\/\/www.saypro.com.tr\/en\/product-categories\/industrial-robot\/\" class=\"octf-btn octf-btn-primary\"> Industrial Robot<\/a>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13e4627 ot-traditional elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13e4627\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d23014 ot-flex-column-vertical\" data-id=\"3d23014\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c41ee9d elementor-widget elementor-widget-spacer\" data-id=\"c41ee9d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AC Drive Products PLC Controller Servo Motor and Control HMI Panel CNC Controller Industrial Robot<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10181","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/pages\/10181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/comments?post=10181"}],"version-history":[{"count":0,"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/pages\/10181\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.saypro.com.tr\/en\/wp-json\/wp\/v2\/media?parent=10181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}